{"id":242,"count":0,"description":"","link":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/","name":"San Gallo","slug":"san-gallo","taxonomy":"adoptapet-canton","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>San Gallo Archive - Protezione Svizzera degli Animali PSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Gallo Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/\" \/>\n<meta property=\"og:site_name\" content=\"Protezione Svizzera degli Animali PSA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/adoptapet-kantone\\\/san-gallo\\\/\",\"url\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/adoptapet-kantone\\\/san-gallo\\\/\",\"name\":\"San Gallo Archive - Protezione Svizzera degli Animali PSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/adoptapet-kantone\\\/san-gallo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/adoptapet-kantone\\\/san-gallo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Gallo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#website\",\"url\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/\",\"name\":\"tierschutz.com\",\"description\":\"Wir setzen uns f\u00fcr das Wohl der Tiere ein.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#organization\"},\"alternateName\":\"Schweizer Tierschutz STS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#organization\",\"name\":\"Schweizer Tierschutz STS\",\"alternateName\":\"STS\",\"url\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"contentUrl\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"caption\":\"Schweizer Tierschutz STS\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schweizertierschutz\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schweizertierschutzsts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@STS_Tierschutz\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/schweizertierschutzsts\\\/\"],\"description\":\"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.\",\"email\":\"sts@tierschutz.com\",\"telephone\":\"061 365 99 99\",\"legalName\":\"Schweizer Tierschutz STS\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"San Gallo Archive - Protezione Svizzera degli Animali PSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/","og_locale":"it_IT","og_type":"article","og_title":"San Gallo Archive","og_url":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/","og_site_name":"Protezione Svizzera degli Animali PSA","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/","url":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/","name":"San Gallo Archive - Protezione Svizzera degli Animali PSA","isPartOf":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#website"},"breadcrumb":{"@id":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/tierschutz.com\/it\/adoptapet-kantone\/san-gallo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/tierschutz.com\/it\/"},{"@type":"ListItem","position":2,"name":"San Gallo"}]},{"@type":"WebSite","@id":"https:\/\/mail.protezione-animali-psa.ch\/#website","url":"https:\/\/mail.protezione-animali-psa.ch\/","name":"tierschutz.com","description":"Wir setzen uns f\u00fcr das Wohl der Tiere ein.","publisher":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#organization"},"alternateName":"Schweizer Tierschutz STS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.protezione-animali-psa.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.protezione-animali-psa.ch\/#organization","name":"Schweizer Tierschutz STS","alternateName":"STS","url":"https:\/\/mail.protezione-animali-psa.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.protezione-animali-psa.ch\/#\/schema\/logo\/image\/","url":"https:\/\/tierschutz.com\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","contentUrl":"https:\/\/tierschutz.com\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","caption":"Schweizer Tierschutz STS"},"image":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schweizertierschutz\/","https:\/\/www.instagram.com\/schweizertierschutzsts\/","https:\/\/www.youtube.com\/@STS_Tierschutz","https:\/\/www.linkedin.com\/company\/schweizertierschutzsts\/"],"description":"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.","email":"sts@tierschutz.com","telephone":"061 365 99 99","legalName":"Schweizer Tierschutz STS"}]}},"_links":{"self":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/adoptapet-canton\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/adoptapet-canton"}],"about":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/taxonomies\/adoptapet-canton"}],"wp:post_type":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/adoptapet?adoptapet-canton=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}