{"id":26126,"date":"2023-08-18T17:33:07","date_gmt":"2023-08-18T15:33:07","guid":{"rendered":"https:\/\/tierschutz.com\/exhibit\/tierpark-biel\/"},"modified":"2024-08-19T09:56:33","modified_gmt":"2024-08-19T07:56:33","slug":"tierpark-biel","status":"publish","type":"exhibit","link":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/","title":{"rendered":"Tierpark Biel"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull\" style=\"min-height:550px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-black-background-color has-background-dim-20 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"507\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg\" class=\"wp-block-cover__image-background wp-post-image\" alt=\"Tierpark Biel\" data-object-fit=\"cover\" data-object-position=\"36% 71%\" style=\"object-position:36% 71%;\" srcset=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg 886w, https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1-300x172.jpg 300w, https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1-768x439.jpg 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\"><div class=\"taxonomy-category has-text-color has-secondary-color has-background has-background-background-color wp-block-post-terms\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull anchor-bar has-lightgray-background-color has-background is-layout-constrained wp-container-core-group-is-layout-47c45fa3 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-left is-layout-flex wp-container-core-group-is-layout-0381e16e wp-block-group-is-layout-flex\">\n<p class=\"link-back has-large-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/tierschutz.com\/it\/project\/rapporto-sugli-zoo\/\">Ritorno ai Rapporto sugli zoo<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" id=\"h-tierpark-biel\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Tierpark Biel<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h1>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<div class=\"wp-block-group is-content-justification-center is-layout-constrained wp-container-core-group-is-layout-3e15952e wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-a96148a1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">Rapporto da <strong>2019\u20132020<\/strong><\/mark><\/p>\n\n\n<div class=\"taxonomy-category has-text-color has-secondary-color has-background has-background-background-color wp-block-post-terms\"><div href=\"https:\/\/tierschutz.com\/exhibit-tag\/espace-mittelland\/\" rel=\"tag\">Espace Mittelland<\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.zoobasel.ch\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"http:\/\/www.tierpark-biel.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.tierpark-biel.ch<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso. Qui sono ospitate quasi esclusivamente specie autoctone. Il parco \u00e8 anche in grado di accogliere e curare animali selvatici feriti o orfani, raccolti dall&#8217;organizzazione faunistica con l&#8217;obiettivo di reintrodurli in natura. Una quantit\u00e0 limitata di cibo per capre nane, mufloni e cervi viene venduta in self-service. Le capre nane, in particolare, reagiscono con forza ai sacchetti di cibo e mostrano un chiaro comportamento di accattonaggio. Le informazioni bilingue per i visitatori sono adeguate. Un parco con alcune strutture esemplari, ma anche alcune che non sono posizionate o attrezzate per soddisfare le esigenze degli animali ospitati.<\/p>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group width100 is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-file-wrapper is-pdf\" data-filetype=\"PDF\" data-size=\"191 KB\">\n<div class=\"wp-block-file width100\"><a id=\"wp-block-file--media-226fc227-0509-4823-8a63-bd91327ee532\" href=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/07\/zb-ml-tierparkbiel.pdf\">Tierpark Biel (PDF in tedesco)<\/a><a href=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/07\/zb-ml-tierparkbiel.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-226fc227-0509-4823-8a63-bd91327ee532\">Scaricare<\/a><\/div>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso. Qui sono ospitate quasi esclusivamente specie autoctone.<\/p>\n","protected":false},"featured_media":9891,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"exhibit-category":[305,82],"exhibit-tag":[91],"class_list":["post-26126","exhibit","type-exhibit","status-publish","has-post-thumbnail","hentry","exhibit-category-103-it","exhibit-category-rapporto-sugli-zoo","exhibit-tag-espace-mittelland"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2013, Rapporto sugli zoo Tierpark Biel - Schweizer Tierschutz STS<\/title>\n<meta name=\"description\" content=\"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tierpark Biel\" \/>\n<meta property=\"og:description\" content=\"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/\" \/>\n<meta property=\"og:site_name\" content=\"Protezione Svizzera degli Animali PSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schweizertierschutz\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-19T07:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"886\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/\",\"url\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/\",\"name\":\"\u2013, Rapporto sugli zoo Tierpark Biel - Schweizer Tierschutz STS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2023\\\/08\\\/EM_Tierpark-Biel1.jpg\",\"datePublished\":\"2023-08-18T15:33:07+00:00\",\"dateModified\":\"2024-08-19T07:56:33+00:00\",\"description\":\"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2023\\\/08\\\/EM_Tierpark-Biel1.jpg\",\"contentUrl\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2023\\\/08\\\/EM_Tierpark-Biel1.jpg\",\"width\":886,\"height\":507,\"caption\":\"Tierpark Biel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/tierpark-biel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Berichte\",\"item\":\"https:\\\/\\\/tierschutz.com\\\/it\\\/exhibit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tierpark Biel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#website\",\"url\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/\",\"name\":\"tierschutz.com\",\"description\":\"Wir setzen uns f\u00fcr das Wohl der Tiere ein.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#organization\"},\"alternateName\":\"Schweizer Tierschutz STS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#organization\",\"name\":\"Schweizer Tierschutz STS\",\"alternateName\":\"STS\",\"url\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"contentUrl\":\"https:\\\/\\\/tierschutz.com\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"caption\":\"Schweizer Tierschutz STS\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schweizertierschutz\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schweizertierschutzsts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@STS_Tierschutz\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/schweizertierschutzsts\\\/\"],\"description\":\"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.\",\"email\":\"sts@tierschutz.com\",\"telephone\":\"061 365 99 99\",\"legalName\":\"Schweizer Tierschutz STS\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2013, Rapporto sugli zoo Tierpark Biel - Schweizer Tierschutz STS","description":"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/","og_locale":"it_IT","og_type":"article","og_title":"Tierpark Biel","og_description":"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.","og_url":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/","og_site_name":"Protezione Svizzera degli Animali PSA","article_publisher":"https:\/\/www.facebook.com\/schweizertierschutz\/","article_modified_time":"2024-08-19T07:56:33+00:00","og_image":[{"width":886,"height":507,"url":"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/","url":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/","name":"\u2013, Rapporto sugli zoo Tierpark Biel - Schweizer Tierschutz STS","isPartOf":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/#primaryimage"},"image":{"@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/#primaryimage"},"thumbnailUrl":"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg","datePublished":"2023-08-18T15:33:07+00:00","dateModified":"2024-08-19T07:56:33+00:00","description":"Lo Tierpark Biel, situato in alto sul B\u00f6zingerberg sopra la citt\u00e0 di Biel, \u00e8 liberamente accessibile. Questo parco di medie dimensioni \u00e8 immerso in un bosco roccioso.","breadcrumb":{"@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/#primaryimage","url":"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg","contentUrl":"https:\/\/tierschutz.com\/app\/uploads\/2023\/08\/EM_Tierpark-Biel1.jpg","width":886,"height":507,"caption":"Tierpark Biel"},{"@type":"BreadcrumbList","@id":"https:\/\/tierschutz.com\/it\/exhibit\/tierpark-biel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/tierschutz.com\/it\/"},{"@type":"ListItem","position":2,"name":"Berichte","item":"https:\/\/tierschutz.com\/it\/exhibit\/"},{"@type":"ListItem","position":3,"name":"Tierpark Biel"}]},{"@type":"WebSite","@id":"https:\/\/mail.protezione-animali-psa.ch\/#website","url":"https:\/\/mail.protezione-animali-psa.ch\/","name":"tierschutz.com","description":"Wir setzen uns f\u00fcr das Wohl der Tiere ein.","publisher":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#organization"},"alternateName":"Schweizer Tierschutz STS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.protezione-animali-psa.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.protezione-animali-psa.ch\/#organization","name":"Schweizer Tierschutz STS","alternateName":"STS","url":"https:\/\/mail.protezione-animali-psa.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.protezione-animali-psa.ch\/#\/schema\/logo\/image\/","url":"https:\/\/tierschutz.com\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","contentUrl":"https:\/\/tierschutz.com\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","caption":"Schweizer Tierschutz STS"},"image":{"@id":"https:\/\/mail.protezione-animali-psa.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schweizertierschutz\/","https:\/\/www.instagram.com\/schweizertierschutzsts\/","https:\/\/www.youtube.com\/@STS_Tierschutz","https:\/\/www.linkedin.com\/company\/schweizertierschutzsts\/"],"description":"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.","email":"sts@tierschutz.com","telephone":"061 365 99 99","legalName":"Schweizer Tierschutz STS"}]}},"_links":{"self":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit\/26126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit"}],"about":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/types\/exhibit"}],"version-history":[{"count":1,"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit\/26126\/revisions"}],"predecessor-version":[{"id":26128,"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit\/26126\/revisions\/26128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/media\/9891"}],"wp:attachment":[{"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/media?parent=26126"}],"wp:term":[{"taxonomy":"exhibit-category","embeddable":true,"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit-category?post=26126"},{"taxonomy":"exhibit-tag","embeddable":true,"href":"https:\/\/tierschutz.com\/it\/wp-json\/wp\/v2\/exhibit-tag?post=26126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}